{"id":1,"date":"2019-06-29T15:41:24","date_gmt":"2019-06-29T13:41:24","guid":{"rendered":"http:\/\/xn--trouvermalibertintrieur-pccd.com\/?p=1"},"modified":"2019-06-30T15:53:44","modified_gmt":"2019-06-30T13:53:44","slug":"bonjour-tout-le-monde","status":"publish","type":"post","link":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/","title":{"rendered":"Le Syst\u00e8me Biofeedback EDUCTOR"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"text-align:center\">En effet, le syst\u00e8me de Biofeedback EDUCTOR est con\u00e7u pour corriger la manifestation des sch\u00e9mas de stress et \/ ou \u00e9lectro-stress \u00e0 tous les niveaux de l\u2019individu,  du plus concret au niveau le plus subtil L&rsquo;EDUCTOR est un appareil quantique, assist\u00e9 par ordinateur permettant des modalit\u00e9s th\u00e9rapeutiques non-invasives qui combinent la bior\u00e9sonance et le biofeedback pour l&rsquo;analyse des param\u00e8tres bio-\u00e9nerg\u00e9tiques du corps et pour r\u00e9tablir le flot de l&rsquo;\u00e9nergie. C\u2019est un syst\u00e8me de gestion du stress qui mesure les r\u00e9actions et les sch\u00e9mas \u00e9lectrophysiologiques au moyen de capteurs \u00e9lectro-magn\u00e9tiques attach\u00e9s \u00e0 la t\u00eate, aux chevilles et aux poignets. Ces r\u00e9actions \u00e9lectrophysiologiques sont catalogu\u00e9es, analys\u00e9es et des fr\u00e9quences harmonisantes sont renvoy\u00e9es \u00e0 l&rsquo;individu selon ses besoins. L\u2019appareil EDUCTOR utilise la technologie de biofeedback voltamm\u00e9trique transcutan\u00e9e. L\u2019appareil se compose d&rsquo;un bo\u00eetier d&rsquo;interface num\u00e9rique connect\u00e9 \u00e0 un ordinateur avec des \u00e9lectrodes attach\u00e9es aux poignets, aux chevilles, et 8 capteurs sur le front de la personne (constituant ainsi 12 points de contact avec le client). Le logiciel est une plate-forme bas\u00e9e sur PC avec des capacit\u00e9s de calculs math\u00e9matiques et graphiques ultra-sophistiqu\u00e9es. L\u2019EDUCTOR mesure le corps \u00e9lectrique \u00e0 12 points pour obtenir des mesures sp\u00e9cifiques de l&rsquo;EEG, EMG, ECG et GSR. Il peut faire des mesures globales des profils de r\u00e9activit\u00e9 \u00e9lectrophysiologique transcutan\u00e9e (TVEP). Les profils aberrants peuvent \u00eatre corrig\u00e9s en utilisant une stimulation par micro-courant. Le logiciel est programm\u00e9 pour s\u2019ajuster automatiquement aux besoins du corps \u00e9lectrique du client pour r\u00e9duire l\u2019\u00e9lectro-stress et permettre au praticien d\u2019informer le client sur des choix de style de vie sains. L&rsquo;EDUCTOR est con\u00e7u pour corriger la manifestation des sch\u00e9mas du stress et\/ou \u00e9lectro-stress au sein de l&rsquo;individu \u00e0 tous les niveaux (physique, mental, \u00e9motionnel, spirituel).  L&rsquo;appareil fonctionne sur le postulat que le stress perturbe les fr\u00e9quences \u00e9lectromagn\u00e9tiques inh\u00e9rentes auxquelles les cellules et organes du corps r\u00e9sonnent et qu&rsquo;en r\u00e9-harmonisant ces fr\u00e9quences \u00e0 leur \u00e9tat naturel, le stress et toute maladie r\u00e9sultant de ces perturbations peuvent \u00eatre corrig\u00e9s.  Des \u00e9tudes ont montr\u00e9 que les gens qui sont trop stress\u00e9s produisent des mod\u00e8les d&rsquo;ondes c\u00e9r\u00e9brales diff\u00e9rents de ceux produits par des gens qui ne sont pas stress\u00e9s, et que l&rsquo;inversion de ce stress, en particulier gr\u00e2ce \u00e0 des techniques telles que le biofeedback peut  faire en sorte que ce qui est anormal devienne normal.  L\u2019EDUCTOR fait une lecture des diff\u00e9rents niveaux de stress physiologiques de l&rsquo;organisme et utilise ces informations pour contr\u00f4ler la physiologie, et par cons\u00e9quent  pour diminuer  les niveaux de stress, ce qui am\u00e9liore la vitalit\u00e9 sur le plan physique et \u00e9motionnel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En effet, le syst\u00e8me de Biofeedback EDUCTOR est con\u00e7u pour corriger la manifestation des sch\u00e9mas de stress et \/ ou \u00e9lectro-stress \u00e0 tous les niveaux de l\u2019individu, du plus concret au niveau le plus subtil L&rsquo;EDUCTOR est un appareil quantique, assist\u00e9 par ordinateur permettant des modalit\u00e9s th\u00e9rapeutiques non-invasives qui combinent la bior\u00e9sonance et le biofeedback [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-systeme-de-biofeedback-et-de-bio-resonnance-le-plus-avance"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Syst\u00e8me Biofeedback EDUCTOR - Th\u00e9rapie Quantique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Syst\u00e8me Biofeedback EDUCTOR - Th\u00e9rapie Quantique\" \/>\n<meta property=\"og:description\" content=\"En effet, le syst\u00e8me de Biofeedback EDUCTOR est con\u00e7u pour corriger la manifestation des sch\u00e9mas de stress et \/ ou \u00e9lectro-stress \u00e0 tous les niveaux de l\u2019individu, du plus concret au niveau le plus subtil L&rsquo;EDUCTOR est un appareil quantique, assist\u00e9 par ordinateur permettant des modalit\u00e9s th\u00e9rapeutiques non-invasives qui combinent la bior\u00e9sonance et le biofeedback [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"Th\u00e9rapie Quantique\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-29T13:41:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-30T13:53:44+00:00\" \/>\n<meta name=\"author\" content=\"Jean-Claude DESCHAUX-BEAUME\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean-Claude DESCHAUX-BEAUME\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/\"},\"author\":{\"name\":\"Jean-Claude DESCHAUX-BEAUME\",\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#\\\/schema\\\/person\\\/421f0bd4487c71e12d2e77415d331f17\"},\"headline\":\"Le Syst\u00e8me Biofeedback EDUCTOR\",\"datePublished\":\"2019-06-29T13:41:24+00:00\",\"dateModified\":\"2019-06-30T13:53:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/\"},\"wordCount\":489,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#organization\"},\"articleSection\":[\"FONCTIONNEMENT DE L'EDUCTOR - SCIO - MARSEILLE\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/\",\"url\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/\",\"name\":\"Le Syst\u00e8me Biofeedback EDUCTOR - Th\u00e9rapie Quantique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#website\"},\"datePublished\":\"2019-06-29T13:41:24+00:00\",\"dateModified\":\"2019-06-30T13:53:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/2019\\\/06\\\/29\\\/bonjour-tout-le-monde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FONCTIONNEMENT DE L'EDUCTOR - SCIO - MARSEILLE\",\"item\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/index.php\\\/cat\\\/systeme-de-biofeedback-et-de-bio-resonnance-le-plus-avance\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le Syst\u00e8me Biofeedback EDUCTOR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#website\",\"url\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/\",\"name\":\"Th\u00e9rapie Quantique\",\"description\":\"EDUCTOR \u00e0 Marseille-Th\u00e9rapie quantique-Scio-Eductor\",\"publisher\":{\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#organization\",\"name\":\"Th\u00e9rapie Quantique Marseille\",\"url\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ScreenHunter-375-2.png\",\"contentUrl\":\"http:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ScreenHunter-375-2.png\",\"width\":389,\"height\":232,\"caption\":\"Th\u00e9rapie Quantique Marseille\"},\"image\":{\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xn--trouvermalibertintrieur-pccd.com\\\/#\\\/schema\\\/person\\\/421f0bd4487c71e12d2e77415d331f17\",\"name\":\"Jean-Claude DESCHAUX-BEAUME\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d4f18ad90c4c43951c006b9e740637ae9befa4c1f76e24ca5400e96bf4c5ca6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d4f18ad90c4c43951c006b9e740637ae9befa4c1f76e24ca5400e96bf4c5ca6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d4f18ad90c4c43951c006b9e740637ae9befa4c1f76e24ca5400e96bf4c5ca6?s=96&d=mm&r=g\",\"caption\":\"Jean-Claude DESCHAUX-BEAUME\"},\"description\":\"Kin\u00e9siologie - Th\u00e9rapie Quantique - Biofeedback - Rebirth -\",\"sameAs\":[\"http:\\\/\\\/trouvermalibert\u00e9int\u00e9rieur.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Syst\u00e8me Biofeedback EDUCTOR - Th\u00e9rapie Quantique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Syst\u00e8me Biofeedback EDUCTOR - Th\u00e9rapie Quantique","og_description":"En effet, le syst\u00e8me de Biofeedback EDUCTOR est con\u00e7u pour corriger la manifestation des sch\u00e9mas de stress et \/ ou \u00e9lectro-stress \u00e0 tous les niveaux de l\u2019individu, du plus concret au niveau le plus subtil L&rsquo;EDUCTOR est un appareil quantique, assist\u00e9 par ordinateur permettant des modalit\u00e9s th\u00e9rapeutiques non-invasives qui combinent la bior\u00e9sonance et le biofeedback [&hellip;]","og_url":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/","og_site_name":"Th\u00e9rapie Quantique","article_published_time":"2019-06-29T13:41:24+00:00","article_modified_time":"2019-06-30T13:53:44+00:00","author":"Jean-Claude DESCHAUX-BEAUME","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jean-Claude DESCHAUX-BEAUME","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/#article","isPartOf":{"@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/"},"author":{"name":"Jean-Claude DESCHAUX-BEAUME","@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#\/schema\/person\/421f0bd4487c71e12d2e77415d331f17"},"headline":"Le Syst\u00e8me Biofeedback EDUCTOR","datePublished":"2019-06-29T13:41:24+00:00","dateModified":"2019-06-30T13:53:44+00:00","mainEntityOfPage":{"@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/"},"wordCount":489,"commentCount":1,"publisher":{"@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#organization"},"articleSection":["FONCTIONNEMENT DE L'EDUCTOR - SCIO - MARSEILLE"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/","url":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/","name":"Le Syst\u00e8me Biofeedback EDUCTOR - Th\u00e9rapie Quantique","isPartOf":{"@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#website"},"datePublished":"2019-06-29T13:41:24+00:00","dateModified":"2019-06-30T13:53:44+00:00","breadcrumb":{"@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/2019\/06\/29\/bonjour-tout-le-monde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/"},{"@type":"ListItem","position":2,"name":"FONCTIONNEMENT DE L'EDUCTOR - SCIO - MARSEILLE","item":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/cat\/systeme-de-biofeedback-et-de-bio-resonnance-le-plus-avance\/"},{"@type":"ListItem","position":3,"name":"Le Syst\u00e8me Biofeedback EDUCTOR"}]},{"@type":"WebSite","@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#website","url":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/","name":"Th\u00e9rapie Quantique","description":"EDUCTOR \u00e0 Marseille-Th\u00e9rapie quantique-Scio-Eductor","publisher":{"@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#organization","name":"Th\u00e9rapie Quantique Marseille","url":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#\/schema\/logo\/image\/","url":"http:\/\/xn--trouvermalibertintrieur-pccd.com\/wp-content\/uploads\/2019\/06\/ScreenHunter-375-2.png","contentUrl":"http:\/\/xn--trouvermalibertintrieur-pccd.com\/wp-content\/uploads\/2019\/06\/ScreenHunter-375-2.png","width":389,"height":232,"caption":"Th\u00e9rapie Quantique Marseille"},"image":{"@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/#\/schema\/person\/421f0bd4487c71e12d2e77415d331f17","name":"Jean-Claude DESCHAUX-BEAUME","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3d4f18ad90c4c43951c006b9e740637ae9befa4c1f76e24ca5400e96bf4c5ca6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3d4f18ad90c4c43951c006b9e740637ae9befa4c1f76e24ca5400e96bf4c5ca6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d4f18ad90c4c43951c006b9e740637ae9befa4c1f76e24ca5400e96bf4c5ca6?s=96&d=mm&r=g","caption":"Jean-Claude DESCHAUX-BEAUME"},"description":"Kin\u00e9siologie - Th\u00e9rapie Quantique - Biofeedback - Rebirth -","sameAs":["http:\/\/trouvermalibert\u00e9int\u00e9rieur.com"]}]}},"_links":{"self":[{"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":1,"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":38,"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions\/38"}],"wp:attachment":[{"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--trouvermalibertintrieur-pccd.com\/index.php\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}